﻿{"id":860,"date":"2019-05-15T09:00:32","date_gmt":"2019-05-15T12:00:32","guid":{"rendered":"https:\/\/www.bfamedicinadotrabalho.com.br\/novo\/?p=860"},"modified":"2019-04-18T12:39:10","modified_gmt":"2019-04-18T15:39:10","slug":"perda-auditiva-produtos-quimicos","status":"publish","type":"post","link":"https:\/\/www.bfamedicinadotrabalho.com.br\/novo\/perda-auditiva-produtos-quimicos\/","title":{"rendered":"Perda auditiva causada por produtos qu\u00edmicos"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft size-full wp-image-857\" src=\"https:\/\/www.bfamedicinadotrabalho.com.br\/novo\/wp-content\/uploads\/2019\/04\/perda-auditiva-produtos-quimicos.jpg\" alt=\"perda-auditiva-produtos-quimicos\" width=\"325\" height=\"237\" srcset=\"https:\/\/www.bfamedicinadotrabalho.com.br\/novo\/wp-content\/uploads\/2019\/04\/perda-auditiva-produtos-quimicos.jpg 325w, https:\/\/www.bfamedicinadotrabalho.com.br\/novo\/wp-content\/uploads\/2019\/04\/perda-auditiva-produtos-quimicos-300x219.jpg 300w\" sizes=\"(max-width: 325px) 100vw, 325px\" \/>A perda auditiva n\u00e3o \u00e9 causada apenas por ru\u00eddo, a exposi\u00e7\u00e3o qu\u00edmica pode prejudicar a audi\u00e7\u00e3o ou intensificar preju\u00edzo causado por ru\u00eddo.<\/p>\n<p>Os produtos qu\u00edmicos otot\u00f3xicos s\u00e3o classificados como neurot\u00f3xicos, cocleot\u00f3xicos ou vestibulot\u00f3xicos. De acordo com a parte que danificam, podem alcan\u00e7ar o ouvido atrav\u00e9s da corrente sangu\u00ednea e causar danos \u00e0s suas partes internas e vias neurais. Os efeitos na sa\u00fade podem ser tempor\u00e1rios ou permanentes dependendo da frequ\u00eancia de exposi\u00e7\u00e3o, intensidade, dura\u00e7\u00e3o e exposi\u00e7\u00e3o a outros riscos no ambiente de trabalho, al\u00e9m de fatores individuais como a idade e sinergia com o ru\u00eddo.<\/p>\n<p>Para prevenir identifique se h\u00e1 produtos otot\u00f3xicos no ambiente de trabalho, revisando as fichas de dados de seguran\u00e7a das subst\u00e2ncias, tais como: solventes, asfixiantes, nitrilas e metais compostos. Caso identificado, verifique a possibilidade de substituir o produto por outro menos t\u00f3xico. Caso n\u00e3o seja poss\u00edvel eliminar, \u00e9 obrigat\u00f3rio o uso de controles de engenharia, tais como: isolamento, ventila\u00e7\u00e3o, visando reduzir o risco de efeitos adversos \u00e0 sa\u00fade. \u00c9 obriga\u00e7\u00e3o da empresa avaliar, determinar e fornecer os Equipamentos de Prote\u00e7\u00e3o Individuais apropriados para garantir a seguran\u00e7a, tais como as m\u00e1scaras, luvas de prote\u00e7\u00e3o contra produtos qu\u00edmicos, mangotes, avental e vestimentas, entre outros. Um bom treinamento de sa\u00fade e seguran\u00e7a bem como o treinamento dos trabalhadores expostos a produtos qu\u00edmicos otot\u00f3xicos evitar\u00e1 maiores consequ\u00eancias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A perda auditiva n\u00e3o \u00e9 causada apenas por ru\u00eddo, a exposi\u00e7\u00e3o qu\u00edmica pode prejudicar a audi\u00e7\u00e3o ou intensificar preju\u00edzo causado &#8230; <a class=\"cz_readmore\" href=\"https:\/\/www.bfamedicinadotrabalho.com.br\/novo\/perda-auditiva-produtos-quimicos\/\"><i class=\"fa czico-107-web-link\" aria-hidden=\"true\"><\/i><span>LEIA MAIS<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":857,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/www.bfamedicinadotrabalho.com.br\/novo\/wp-json\/wp\/v2\/posts\/860"}],"collection":[{"href":"https:\/\/www.bfamedicinadotrabalho.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bfamedicinadotrabalho.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bfamedicinadotrabalho.com.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bfamedicinadotrabalho.com.br\/novo\/wp-json\/wp\/v2\/comments?post=860"}],"version-history":[{"count":1,"href":"https:\/\/www.bfamedicinadotrabalho.com.br\/novo\/wp-json\/wp\/v2\/posts\/860\/revisions"}],"predecessor-version":[{"id":861,"href":"https:\/\/www.bfamedicinadotrabalho.com.br\/novo\/wp-json\/wp\/v2\/posts\/860\/revisions\/861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bfamedicinadotrabalho.com.br\/novo\/wp-json\/wp\/v2\/media\/857"}],"wp:attachment":[{"href":"https:\/\/www.bfamedicinadotrabalho.com.br\/novo\/wp-json\/wp\/v2\/media?parent=860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bfamedicinadotrabalho.com.br\/novo\/wp-json\/wp\/v2\/categories?post=860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bfamedicinadotrabalho.com.br\/novo\/wp-json\/wp\/v2\/tags?post=860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}